{"id":645,"date":"2018-04-17T07:04:37","date_gmt":"2018-04-17T07:04:37","guid":{"rendered":"https:\/\/www.remming.co.rs\/cevovodi\/"},"modified":"2018-04-25T09:38:34","modified_gmt":"2018-04-25T09:38:34","slug":"rohrleitungen","status":"publish","type":"page","link":"https:\/\/www.remming.co.rs\/de\/andere-produkte\/rohrleitungen\/","title":{"rendered":"Rohrleitungen"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"Remming ist hoch spezialisiert im Bereich Planung und Fertigung von Stahlrohrleitungen. Die Planung sowie Fertigung von Rohrleitungen erfolgt \u00fcberwiegend nach EN13480.","protected":false},"author":1,"featured_media":0,"parent":663,"menu_order":7,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-645","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rohrleitungen - Remming<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.remming.co.rs\/de\/andere-produkte\/rohrleitungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rohrleitungen - Remming\" \/>\n<meta property=\"og:description\" content=\"Remming ist hoch spezialisiert im Bereich Planung und Fertigung von Stahlrohrleitungen. Die Planung sowie Fertigung von Rohrleitungen erfolgt \u00fcberwiegend nach EN13480.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.remming.co.rs\/de\/andere-produkte\/rohrleitungen\/\" \/>\n<meta property=\"og:site_name\" content=\"Remming\" \/>\n<meta property=\"article:modified_time\" content=\"2018-04-25T09:38:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.remming.co.rs\\\/de\\\/andere-produkte\\\/rohrleitungen\\\/\",\"url\":\"https:\\\/\\\/www.remming.co.rs\\\/de\\\/andere-produkte\\\/rohrleitungen\\\/\",\"name\":\"Rohrleitungen - Remming\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.remming.co.rs\\\/#website\"},\"datePublished\":\"2018-04-17T07:04:37+00:00\",\"dateModified\":\"2018-04-25T09:38:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.remming.co.rs\\\/de\\\/andere-produkte\\\/rohrleitungen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.remming.co.rs\\\/de\\\/andere-produkte\\\/rohrleitungen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.remming.co.rs\\\/de\\\/andere-produkte\\\/rohrleitungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Andere Produkte\",\"item\":\"https:\\\/\\\/www.remming.co.rs\\\/de\\\/andere-produkte\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rohrleitungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.remming.co.rs\\\/#website\",\"url\":\"https:\\\/\\\/www.remming.co.rs\\\/\",\"name\":\"Remming\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.remming.co.rs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rohrleitungen - Remming","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.remming.co.rs\/de\/andere-produkte\/rohrleitungen\/","og_locale":"de_DE","og_type":"article","og_title":"Rohrleitungen - Remming","og_description":"Remming ist hoch spezialisiert im Bereich Planung und Fertigung von Stahlrohrleitungen. Die Planung sowie Fertigung von Rohrleitungen erfolgt \u00fcberwiegend nach EN13480.","og_url":"https:\/\/www.remming.co.rs\/de\/andere-produkte\/rohrleitungen\/","og_site_name":"Remming","article_modified_time":"2018-04-25T09:38:34+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.remming.co.rs\/de\/andere-produkte\/rohrleitungen\/","url":"https:\/\/www.remming.co.rs\/de\/andere-produkte\/rohrleitungen\/","name":"Rohrleitungen - Remming","isPartOf":{"@id":"https:\/\/www.remming.co.rs\/#website"},"datePublished":"2018-04-17T07:04:37+00:00","dateModified":"2018-04-25T09:38:34+00:00","breadcrumb":{"@id":"https:\/\/www.remming.co.rs\/de\/andere-produkte\/rohrleitungen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.remming.co.rs\/de\/andere-produkte\/rohrleitungen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.remming.co.rs\/de\/andere-produkte\/rohrleitungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Andere Produkte","item":"https:\/\/www.remming.co.rs\/de\/andere-produkte\/"},{"@type":"ListItem","position":2,"name":"Rohrleitungen"}]},{"@type":"WebSite","@id":"https:\/\/www.remming.co.rs\/#website","url":"https:\/\/www.remming.co.rs\/","name":"Remming","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.remming.co.rs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.remming.co.rs\/de\/wp-json\/wp\/v2\/pages\/645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.remming.co.rs\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.remming.co.rs\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.remming.co.rs\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.remming.co.rs\/de\/wp-json\/wp\/v2\/comments?post=645"}],"version-history":[{"count":5,"href":"https:\/\/www.remming.co.rs\/de\/wp-json\/wp\/v2\/pages\/645\/revisions"}],"predecessor-version":[{"id":1187,"href":"https:\/\/www.remming.co.rs\/de\/wp-json\/wp\/v2\/pages\/645\/revisions\/1187"}],"up":[{"embeddable":true,"href":"https:\/\/www.remming.co.rs\/de\/wp-json\/wp\/v2\/pages\/663"}],"wp:attachment":[{"href":"https:\/\/www.remming.co.rs\/de\/wp-json\/wp\/v2\/media?parent=645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}